{"id":12104,"date":"2018-02-01T12:12:21","date_gmt":"2018-02-01T09:12:21","guid":{"rendered":"https:\/\/iibsblogsstg.wpenginepowered.com\/?p=12104\/"},"modified":"2026-06-24T16:54:11","modified_gmt":"2026-06-24T16:54:11","slug":"capitulo-transitorio-1-sus-ojos-estaban-velados","status":"publish","type":"post","link":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/","title":{"rendered":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS"},"content":{"rendered":"<p><b><strong data-start=\"699\" data-end=\"709\">TL;DR:<\/strong><\/b> El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas hasta que sus ojos fueron abiertos por Dios.<\/p>\n<p><b>En el mismo d\u00eda<\/b><\/p>\n<p>Como todos sabemos, Lucas es el \u00fanico autor en el Nuevo Testamento que sinti\u00f3 la necesidad de completar la historia de la vida <i>\u201c<\/i>oculta<i>\u201d<\/i> de Jes\u00fas en el Evangelio, con la historia de sus disc\u00edpulos en Hechos, proclamando aqu\u00ed abiertamente que Jes\u00fas es el Mes\u00edas. M\u00e1s a\u00fan, en su escrito de dos vol\u00famenes, Lucas nos proporciona una formidable herramienta para entender la naturaleza del abrupto cambio entre el Evangelio y Hechos: \u00bfPor qu\u00e9 el estatus mesi\u00e1nico de Jes\u00fas, escondido tan a fondo en el Evangelio, de repente empieza a ser proclamado p\u00fablicamente en Hechos? \u00bfPor qu\u00e9 <i>lo que fue hablado al o\u00eddo en c\u00e1maras secretas <\/i>en el Evangelio, es <i>\u201cproclamado desde las azoteas\u201d<\/i> en Hechos? El \u00faltimo cap\u00edtulo del Evangelio de Lucas sirve no solo como una maravillosa transici\u00f3n literaria hacia el segundo volumen, sino tambi\u00e9n como una clave espiritual para toda la historia del mesianismo de Jes\u00fas y la restringida visi\u00f3n de Israel en el escrito de Lucas.<\/p>\n<p>Ustedes recuerdan, por supuesto, esta hermosa historia de los dos disc\u00edpulos en el \u00faltimo cap\u00edtulo del Evangelio de Lucas \u2014c\u00f3mo en el primer d\u00eda de la semana\u2014, ese mismo d\u00eda de <i>Yom Rishon<\/i>, el domingo, que comenz\u00f3 con la asombrosa historia de las mujeres y c\u00f3mo ellas no encontraron el cuerpo de Jes\u00fas , en el mismo d\u00eda, pero horas m\u00e1s tarde, <i>dos de ellos viajaban\u2026 hacia una villa llamada Ema\u00fas\u201d<\/i> (en hebreo es <em>Ammaus<\/em> &#8212; \u05e2\u05de\u05d0\u05d5\u05e1),\u00a0<i>que estaba a 60 estadios<\/i> (como a unas siete millas) <i>de Jerusal\u00e9n.\u00a0<\/i>Podemos imaginar lo que estaba sucediendo en sus corazones y en sus mentes. Estaban absolutamente perplejos de todo lo que hab\u00eda sucedido a su Maestro, y estaban hablando entre ellos sobre estos eventos. Ahora bien, en el camino <i>el mismo Jes\u00fas\u2026 fue con ellos,<\/i> pero ellos no le reconocieron. Siguieron comentando; respondieron a Jes\u00fas cuando \u00c9l les pregunt\u00f3 sobre las \u00faltimas noticias de Jerusal\u00e9n; estaban desconcertados de que \u00c9l no supiese qu\u00e9 hab\u00eda sucedido \u2014pero no le reconocieron\u2014. Entonces \u00c9l dijo algo muy remarcable:\u00a0<i>\u00a1Oh insensatos, y tardos de coraz\u00f3n para creer todo lo que los profetas han dicho!<\/i><em><a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]\u00a0<\/strong><\/a><\/em>Debemos admitir que es realmente dif\u00edcil imaginar a un viajero ocasional diciendo algo tan duro \u2014uno ha de tener una verdadera autoridad para decir estas palabras\u2014 pero a pesar de esas palabras, no le reconocieron. Entonces \u00c9l comenz\u00f3 a ense\u00f1arles sobre las escrituras. Uno podr\u00eda pensar que ellos deber\u00edan haberle recordado, habi\u00e9ndoles ense\u00f1ado tantas veces cuando estaba con ellos, a\u00fan as\u00ed, fueron incapaces de reconocerle. <b><i>Mas los ojos de ellos estaban velados, para que no le conociesen<\/i><\/b>.<strong><em><a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> <\/em><\/strong><\/p>\n<p>Ya vimos que referirse a la venida del Mes\u00edas como <i>oculto <\/i>y <i>revelado <\/i>podr\u00eda tomarse como una representaci\u00f3n del juda\u00edsmo del primer siglo. La idea del mes\u00edas siendo <b>irreconocible<\/b> por el pueblo de Israel, era una idea muy com\u00fan en el pensamiento jud\u00edo. En este sentido, la historia de Ema\u00fas apenas conlleva una prueba adicional a esta idea. Sin embargo, mediante esta historia, Lucas muestra claramente c\u00f3mo y por qu\u00e9 ellos no le reconocieron \u2014y eso es lo que vamos a comentar ahora\u2014.<\/p>\n<p><b>Sus ojos estaban velados<\/b><\/p>\n<p>Intentemos comprender qu\u00e9 sucedi\u00f3 en los ojos de los disc\u00edpulos camino a Ema\u00fas. Leemos que sus ojos <i>estaban velados.<\/i> En ingl\u00e9s, como en griego,\u00a0 el verbo <i>velados<\/i> es la forma pasiva del verbo <em>velar<\/em>. Esencialmente significa que, fuera lo que fuese que les sucediera a los disc\u00edpulos, su incapacidad para reconocer a Jes\u00fas no depend\u00eda de ellos mismos. Alguien estaba <b><i>velando <\/i><\/b>sus ojos hasta que el momento se\u00f1alado llegara.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]\u00a0<\/a>Entonces, cuando el tiempo se\u00f1alado lleg\u00f3, ese mismo <i>alguien<\/i> abri\u00f3 sus ojos: <em>Entonces les fueron abiertos los ojos, y le reconocieron.<a href=\"#_ftn4\" name=\"_ftnref4\"><strong>[4]<\/strong><\/a> <\/em>Una vez m\u00e1s, como en el vers\u00edculo 16, el texto utiliza la forma pasiva: <i>les fueron abiertos los ojos<\/i>. El verbo griego<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>empleado aqu\u00ed significa \u201cser completamente abierto, enteramente\u201d, y ocurre varias veces en la Septuaginta. El uso de la forma activa\u00a0 de este verbo es remarcable. En casi todos los lugares en la Septuaginta, donde este verbo se encuentra en la forma activa, el sujeto de la oraci\u00f3n es Dios mismo, lo cual nos lleva a una conclusi\u00f3n muy importante:\u00a0Dios es el \u00fanico que puede abrir nuestros ojos espirituales. Por ejemplo, en II Reyes 6:17. El\u00edas ruega al Se\u00f1or que abra los ojos de su siervo: <i>\u201cSE\u00d1OR, te ruego,<\/i> <b>abre<\/b> <i>sus ojos para que \u00e9l pueda ver. Y el SE\u00d1OR <\/i><b><i>abri\u00f3 <\/i><\/b><i>los ojos del joven y vio. <\/i>Ese es el porqu\u00e9 de las palabras de Lucas al final del mismo cap\u00edtulo: <i>Entonces les abri\u00f3 el entendimiento, para que comprendiesen las Escritura<\/i><em>s<a href=\"#_ftn6\" name=\"_ftnref6\"><strong>[6]<\/strong><\/a><\/em>, de alguna forma, es una declaraci\u00f3n de fe: Lucas evidentemente cree que Jes\u00fas es Dios y esa es la causa del porqu\u00e9 \u00c9l tiene la autoridad de Dios para <b>abrir<\/b>. Seg\u00fan Lucas, el Se\u00f1or y solo \u00c9l, tiene el poder para <b>velar<\/b> el entendimiento y los ojos \u2014y es el \u00fanico que puede <b>abrir<\/b>, desbloquear el entendimiento y los ojos. Los ojos de los disc\u00edpulos en el camino de Ema\u00fas fueron velados de una manera soberana solamente por Su mano, y de alg\u00fan modo podr\u00edan haber reconocido a Jes\u00fas hasta que \u00c9l mismo abri\u00f3 sus ojos.<\/p>\n<p>Respecto a esto, me gustar\u00eda recordar la conocida escena en la sinagoga de Nazaret del cap\u00edtulo 4 del Evangelio de Lucas: <i>Vino a Nazaret, donde se hab\u00eda criado; y en el d\u00eda de reposo entr\u00f3 en la sinagoga, conforme a su costumbre, y se levant\u00f3 a leer\u2026<\/i> <a href=\"#_ftn7\" name=\"_ftnref7\"><em><strong>[7]\u00a0<\/strong><\/em><\/a>Mientras le\u00eda esos vers\u00edculos, Lucas 4:16:30, uno sin duda se asombra ante el incre\u00edble ambiente tenso que llenaba la sinagoga cuando Jes\u00fas le\u00eda al profeta Isa\u00edas. \u00bfCu\u00e1l es la ra\u00edz de la tensi\u00f3n, y de qu\u00e9 da testimonio? <i>Y los ojos de todos en la sinagoga estaban fijos en \u00e9l\u2026 Y todos daban buen testimonio de \u00e9l, y estaban maravillados de las palabras de gracia que sal\u00edan de su boca<\/i><em>.<a href=\"#_ftn8\" name=\"_ftnref8\"><strong>[8]<\/strong><\/a>\u00a0<\/em>En otras palabras, Lucas\u00a0 muestra un cuadro muy similar al que vimos en el camino de Ema\u00fas: los corazones de aquellos que escucharon a Jes\u00fas, ard\u00edan, estaban claramente sintiendo que Aquel que estaba delante de ellos ten\u00eda una autoridad especial, una autoridad extra humana.\u00a0<i>Y los ojos de todos en la sinagoga estaban fijos en \u00e9l <\/i>con un deseo intenso y esperando ver en \u00c9l a Aquel a quien sent\u00edan en sus corazones, \u00c9l era. Yo creo que ellos deseaban desesperadamente obedecer la voz de sus corazones y reconocerle como Mes\u00edas \u2014\u00bfy aun as\u00ed? \u2014 no pudieron. \u00bfPor qu\u00e9? \u00bfCu\u00e1l fue la diferencia entre los disc\u00edpulos del camino de Ema\u00fas y los conciudadanos de Jes\u00fas en Nazaret? Lucas deja claro que en ambos casos, los corazones ard\u00edan, y en ambos casos los ojos fijos en Jes\u00fas estaban velados por nadie m\u00e1s que por el mismo Se\u00f1or (ya sabemos que en la Biblia nadie m\u00e1s puede velar o abrir los ojos de alguien). Sin embargo, los ojos de los disc\u00edpulos en el camino de Ema\u00fas fueron finalmente abiertos, mientras que los ojos de la gente de Nazaret permanecieron velados\u2026<\/p>\n<p>Este es un mensaje que Lucas transmite a su lector en este cap\u00edtulo transitorio: <b>ninguno, aparte del mismo Dios puede velar o abrir los ojos espirituales<\/b>. Para Lucas, est\u00e1 clara Su decisi\u00f3n, y es solo suya en ambos casos, en el caso de los disc\u00edpulos camino a Ema\u00fas, cuyos ojos al final fueron abiertos y que finalmente le reconocieron, y en el caso de la sinagoga, donde los ojos de la gente permanecieron <i>velados<\/i> y no le reconocieron.<\/p>\n<p><i>Continuar\u00e1\u2026<\/i><\/p>\n<p>(Si est\u00e1s interesado en leer mi libro sobre el Mes\u00edas Oculto u otros libros, puedes obtenerlos en mi p\u00e1gina,\u00a0<a href=\"https:\/\/israelbiblicalstudies.com\/blog\/author\/juliablum\/\">https:\/\/israelbiblicalstudies.com\/blog\/author\/juliablum\/.)<\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Lucas 24.25<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Lucas 24:16<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> En griego, exactamente como en ingl\u00e9s, tenemos la forma pasiva\u00a0<strong>(<\/strong>\u03b5\u03ba\u03c1\u03b1\u03c4\u03bf\u03c5\u03bd\u03c4\u03bf<strong>)\u00a0<\/strong>del verbo <i>velar\u00a0<\/i><strong>(<\/strong>\u039a\u03c1\u03b1\u03c4\u03b5\u03c9<strong>).<\/strong><\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Lucas 24:31<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> \u0394\u03b9\u03b1\u03bd\u03bf\u03b9\u03b3\u03c9<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Lucas 24:45<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> Lucas 4:16<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> Lucas 4:20, 22<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas hasta que sus ojos fueron abiertos por Dios. En el mismo d\u00eda Como todos sabemos, Lucas es el \u00fanico autor en el Nuevo Testamento que sinti\u00f3 la necesidad de completar la historia [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":12101,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[565],"tags":[],"class_list":["post-12104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jewish-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies<\/title>\n<meta name=\"description\" content=\"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies\" \/>\n<meta property=\"og:description\" content=\"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/\" \/>\n<meta property=\"og:site_name\" content=\"Israel Institute of Biblical Studies\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-01T09:12:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T16:54:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"818\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Blum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Blum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/\"},\"author\":{\"name\":\"Julia Blum\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\"},\"headline\":\"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS\",\"datePublished\":\"2018-02-01T09:12:21+00:00\",\"dateModified\":\"2026-06-24T16:54:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/\"},\"wordCount\":1434,\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/shutterstock_96837559.jpg\",\"articleSection\":[\"Estudios Jud\u00edos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/\",\"name\":\"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/shutterstock_96837559.jpg\",\"datePublished\":\"2018-02-01T09:12:21+00:00\",\"dateModified\":\"2026-06-24T16:54:11+00:00\",\"description\":\"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/shutterstock_96837559.jpg\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/shutterstock_96837559.jpg\",\"width\":818,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/capitulo-transitorio-1-sus-ojos-estaban-velados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudios Jud\u00edos\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"name\":\"Israel Institute of Biblical Studies\",\"description\":\"Deepen Your Understanding of the Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\",\"name\":\"Israel Biblical Studies\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"width\":152,\"height\":68,\"caption\":\"Israel Biblical Studies\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\",\"name\":\"Julia Blum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"caption\":\"Julia Blum\"},\"description\":\"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/author\\\/juliablum\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies","description":"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/","og_locale":"es_ES","og_type":"article","og_title":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies","og_description":"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas","og_url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/","og_site_name":"Israel Institute of Biblical Studies","article_published_time":"2018-02-01T09:12:21+00:00","article_modified_time":"2026-06-24T16:54:11+00:00","og_image":[{"width":818,"height":1000,"url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg","type":"image\/jpeg"}],"author":"Julia Blum","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julia Blum","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#article","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/"},"author":{"name":"Julia Blum","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15"},"headline":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS","datePublished":"2018-02-01T09:12:21+00:00","dateModified":"2026-06-24T16:54:11+00:00","mainEntityOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/"},"wordCount":1434,"publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg","articleSection":["Estudios Jud\u00edos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/","name":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS - Israel Institute of Biblical Studies","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#primaryimage"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg","datePublished":"2018-02-01T09:12:21+00:00","dateModified":"2026-06-24T16:54:11+00:00","description":"TL;DR: El camino a Ema\u00fas revela una dimensi\u00f3n profunda del reconocimiento espiritual. Este estudio analiza por qu\u00e9 los disc\u00edpulos no reconocieron a Jes\u00fas","breadcrumb":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#primaryimage","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/02\/shutterstock_96837559.jpg","width":818,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/capitulo-transitorio-1-sus-ojos-estaban-velados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/israelbiblicalstudies.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estudios Jud\u00edos","item":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/"},{"@type":"ListItem","position":3,"name":"CAP\u00cdTULO TRANSITORIO (1) SUS OJOS ESTABAN VELADOS"}]},{"@type":"WebSite","@id":"https:\/\/israelbiblicalstudies.com\/es\/#website","url":"https:\/\/israelbiblicalstudies.com\/es\/","name":"Israel Institute of Biblical Studies","description":"Deepen Your Understanding of the Bible","publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/israelbiblicalstudies.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization","name":"Israel Biblical Studies","url":"https:\/\/israelbiblicalstudies.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","width":152,"height":68,"caption":"Israel Biblical Studies"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15","name":"Julia Blum","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","caption":"Julia Blum"},"description":"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/author\/juliablum\/"}]}},"_links":{"self":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/12104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/comments?post=12104"}],"version-history":[{"count":1,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/12104\/revisions"}],"predecessor-version":[{"id":61257,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/12104\/revisions\/61257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media\/12101"}],"wp:attachment":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media?parent=12104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/categories?post=12104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/tags?post=12104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}