{"id":12237,"date":"2018-04-11T18:41:41","date_gmt":"2018-04-11T15:41:41","guid":{"rendered":"https:\/\/iibsblogsstg.wpenginepowered.com\/?p=12237"},"modified":"2025-08-13T11:29:26","modified_gmt":"2025-08-13T11:29:26","slug":"retratos-biblicos-juda-1","status":"publish","type":"post","link":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/","title":{"rendered":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1)"},"content":{"rendered":"<p>\u00bfPOR QU\u00c9 JUD\u00c1?<\/p>\n<p>Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el calendario jud\u00edo, y este a\u00f1o se celebrar\u00e1 muy pronto, el 18-19 de abril). En un principio plane\u00e9 escribir algo especial en este post sobre el Estado de Israel, pero me di cuenta de que probablemente ustedes saben tanto como yo al respecto y aunque no fuese as\u00ed, existen much\u00edsimos art\u00edculos sobre Israel en Internet, especialmente en esta feliz ocasi\u00f3n. Pero como saben, este es un blog de Estudios B\u00edblicos \u2014y personalmente me sent\u00ed dirigida a comentar algo sobre el Jud\u00e1 b\u00edblico\u2014.<\/p>\n<p>S\u00ed, Jud\u00e1 del libro de G\u00e9nesis, el hijo de Jacob y hermano de Jos\u00e9. Podr\u00edan preguntarse, \u00bfpor qu\u00e9 Jud\u00e1? \u00bfQu\u00e9 tiene que ver Jud\u00e1 con el aniversario de Israel? M\u00e1s adelante, en la Biblia, Jud\u00e1 viene a representar el reino del sur, cuya capital es Jerusal\u00e9n, mientras que Israel era el nombre del reino del norte. A primera vista, el retrato b\u00edblico que vamos a describir aqu\u00ed, parece no estar conectado del todo con el 70\u00ba aniversario de Israel. A\u00fan as\u00ed, todos sabemos que el Rey David \u2014quien es el s\u00edmbolo del Israel Unido y el prototipo y s\u00edmbolo de Mes\u00edas\u2014 fue descendiente de Jud\u00e1. El libro de Samuel lo deja muy claro, Dios otorga Su unci\u00f3n, para siempre, en la l\u00ednea mon\u00e1rquica que proviene de la tribu de Jud\u00e1 en la persona del Rey David. Y Jes\u00fas, quien es designado como \u2018Hijo de David\u2019, tambi\u00e9n es descendiente de Jud\u00e1. Por eso, el retrato de Jud\u00e1 tiene mucho que ver, tanto con Israel como con la fe cristiana. Cuando los israelitas cantan <i>\u201cDavid Melech Israel\u201d<\/i>\u00a0 (David es el Rey de Israel) todo comenz\u00f3 con Jud\u00e1. Y cuando leemos en Apocalipsis sobre el \u201cLe\u00f3n de la tribu de Jud\u00e1\u201d, tambi\u00e9n comenz\u00f3 con Jud\u00e1.<\/p>\n<p>\u00bfAlguna vez se han preguntado por qu\u00e9? \u00bfPor qu\u00e9 fue Jud\u00e1 \u2014cuya debilidad, incluso pecados, est\u00e1n tan claramente revelados en el libro de G\u00e9nesis, tanto en la historia de Jos\u00e9 como en la historia de Tamar\u2014 quien fue honrado con ese extraordinario privilegio? M\u00e1s a\u00fan, si sabemos que la tribu de Jud\u00e1 estaba destinada a tener este honor \u00fanico \u2014traer al Rey David y tambi\u00e9n a Jes\u00fas\u2014 \u00bfc\u00f3mo conectamos los puntos entre este glorioso destino y la cuestionable conducta de Jud\u00e1 en el libro de G\u00e9nesis? Y, una vez m\u00e1s, \u00bfqu\u00e9 tiene que ver todo esto con el 70\u00ba aniversario de Israel?<\/p>\n<p>Vayamos a solucionarlo. \u00bfQui\u00e9n fue Jud\u00e1 y qu\u00e9 sabemos de \u00e9l?<\/p>\n<p>EL COMIENZO<\/p>\n<p>Empecemos por el principio \u2014desde el nacimiento de Jud\u00e1\u2014. Cuando Lea dio a luz a su cuarto hijo, ella dijo<i>: \u201cEsta vez alabar\u00e9<span style=\"font-size: 11.666666030883789px\">\u00a0<\/span><\/i><i>a Jehov\u00e1; <\/i><b><i>por esto<\/i><\/b><i> llam\u00f3 su nombre Jud\u00e1\u201d. <\/i>En ingl\u00e9s, por supuesto, no vemos una conexi\u00f3n: Creo que esto es una de las mayores p\u00e9rdidas que tenemos cuando leemos \u00fanicamente nuestra Biblia traducida \u2014el significado de los nombres hebreos se pierden completamente en la traducci\u00f3n\u2014. Las traducciones y adaptaciones no cambian simplemente el significado original, sino que hacen que el nombre no tenga sentido. A menos que dediquemos tiempo y volvamos al hebreo, los nombres b\u00edblicos de las personas y lugares en la traducci\u00f3n continuar\u00e1n del todo sin conexi\u00f3n con los puntos originales de referencia y con las ideas enterradas en el mismo texto. Las palabras de conexi\u00f3n: \u201cpor cuanto\u201d o \u201cy\u201d o \u201cas\u00ed pues\u201d parecen sin sentido alguno en estos casos \u2014como en G\u00e9nesis 3:20\u00a0 \u201c<i>Y llam\u00f3 Ad\u00e1n el nombre de su mujer, Eva, <\/i><b><i>por cuanto<\/i><\/b><i> ella era madre de todos los vivientes\u201d<\/i> o en G\u00e9nesis 25:26 \u201c<i>Despu\u00e9s sali\u00f3 su hermano, trabada su mano al calca\u00f1ar de Esa\u00fa; <\/i><b><i>y <\/i><\/b><i>fue llamado su nombre Jacob\u201d. <\/i>Sin embargo, cuando leemos las Escrituras en Hebreo, las conexiones son evidentes \u2014y esto est\u00e1 completamente claro en el nombre de Jud\u00e1\u2014:\u00a0el verbo <em>lehodot<\/em> (\u05dc\u05d4\u05d5\u05d3\u05d5\u05ea)\u00a0significa \u201cagradecer\u201d o \u201calabar\u201d y el nombre hebreo de <b><i>Jud\u00e1<\/i><\/b>,\u00a0<em>Yehudah<\/em> (\u05d9\u05d4\u05d5\u05d3\u05d4),\u00a0es el nombre formado por la ra\u00edz\u00a0Y-D-H (\u05d9\u05d3\u05d4),\u00a0\u201c<b><i>agradecer<\/i><\/b><i>\u201d<\/i> o \u201c<i>alabar<\/i>\u201d.<\/p>\n<p>Por eso, el nombre hebreo de Jud\u00e1,\u00a0<em>Yehudah<\/em> (\u05d9\u05d4\u05d5\u05d3\u05d4),\u00a0puede traducirse literalmente como <i>\u201c<\/i><b><i>acci\u00f3n de gracias<\/i><\/b><i>\u201d <\/i>\u2014y esto es algo que muchos de los lectores de la Biblia conocen (incluso aquellos que no saben hebreo) \u2014. Esta es tambi\u00e9n la primera, y muy importante, lecci\u00f3n del nombre de Jud\u00e1: necesitamos <i>agradecer<\/i> al Se\u00f1or para que podamos ser parte de Su plan y de Su historia, y para atraer Sus bendiciones sobre nuestros descendientes. Sin embargo, hay algo m\u00e1s que podemos aprender de este nombre, pero para poderlo hacerlo, necesitamos ir m\u00e1s all\u00e1.<\/p>\n<p>LA HISTORIA M\u00c1S OLVIDADA EN EL LIBRO DE G\u00c9NESIS<\/p>\n<p>Justo despu\u00e9s de que Jos\u00e9 fuese vendido por sus hermanos en G\u00e9nesis 37, leemos la historia de Jud\u00e1 y Tamar en G\u00e9nesis 38. Efectivamente, esta historia rompe el flujo de la narrativa de Jos\u00e9 en lugar de seguir cont\u00e1ndonos como fue la ida de Jos\u00e9 a Egipto, la Tor\u00e1 encuentra que es necesario interrumpirla con la historia de Jud\u00e1. Leemos c\u00f3mo Jud\u00e1 se separa de sus hermanos (y nos preguntamos \u00bfpor qu\u00e9?), de su matrimonio, de la muerte de sus hijos, de la seducci\u00f3n de Tamar, y del cl\u00edmax de la historia \u2014la <b>confesi\u00f3n<\/b> de Jud\u00e1\u2014. A simple vista, esta historia no est\u00e1 conectada en modo alguno con la venta de Jos\u00e9, y su posici\u00f3n en el texto parece fortuita y extra\u00f1a. He estado ense\u00f1ando esta lecci\u00f3n por varios a\u00f1os hasta hoy, y cada vez que pregunto a mis estudiantes: Por favor, \u00bfpueden explicar por qu\u00e9 la historia de Jud\u00e1 fue colocada en medio de la saga de Jos\u00e9? \u00bfPor qu\u00e9 se interrumpe la historia de Jos\u00e9? Hasta hoy, no he recibido ninguna respuesta a estas preguntas.<\/p>\n<p>El cap\u00edtulo 38 abre con estas palabras \u201c<em>Aconteci\u00f3 en aquel tiempo<\/em><i>\u201d. <\/i>Este comienzo ya insin\u00faa alguna conexi\u00f3n entre la narrativa previa y lo que estamos a punto de leer: esta expresi\u00f3n es usada com\u00fanmente para indicar conexiones, tanto cronol\u00f3gicas como tem\u00e1ticas. Entonces leemos \u201c<i>que Jud\u00e1 se apart\u00f3 de sus hermanos<\/i>\u201d.<\/p>\n<p>\u00bfPor qu\u00e9 Jud\u00e1 se march\u00f3?<\/p>\n<p>Volvamos a la historia de la venta. \u00bfSe han dado cuenta que la voz de Jud\u00e1 fue absolutamente decisiva en esta historia? Mientras Rub\u00e9n ten\u00eda buenas intenciones (pero fue incapaz de llevarlas adelante), es de acuerdo con lo sugerido por Jud\u00e1 que el destino de Jos\u00e9 fue decidido y vendido. Incluso en medio de este terrible crimen, somos testigos de la sorprendente autoridad de Jud\u00e1 por primera vez (y definitivamente no la \u00faltima) en la saga de Jos\u00e9. Como veremos m\u00e1s adelante, el coraz\u00f3n de Jud\u00e1 cambiar\u00e1, su car\u00e1cter ser\u00e1 transformado \u2014pero esta incre\u00edble autoridad, el maravilloso don de Dios a esta tribu, estar\u00e1 siempre con \u00e9l\u2014.<\/p>\n<p>Y aqu\u00ed tambi\u00e9n encontramos una explicaci\u00f3n de por qu\u00e9 \u00e9l march\u00f3: leemos en un midrash que los hermanos culparon a Jud\u00e1 y dijeron: \u201ct\u00fa sugeriste que vendi\u00e9semos a Jos\u00e9, y nosotros te seguimos. Si hubieras sugerido que dej\u00e1semos libre a Jos\u00e9, tambi\u00e9n te hubi\u00e9ramos seguido<i>\u201d<\/i>. Esa es la raz\u00f3n por la <i>\u201cque Jud\u00e1 se apart\u00f3 de sus hermanos\u201d.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p><em>Continuar\u00e1\u2026<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el calendario jud\u00edo, y este a\u00f1o se celebrar\u00e1 muy pronto, el 18-19 de abril). En un principio plane\u00e9 escribir algo especial en este post sobre el Estado de Israel, [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":12218,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[565],"tags":[],"class_list":["post-12237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jewish-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies<\/title>\n<meta name=\"description\" content=\"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies\" \/>\n<meta property=\"og:description\" content=\"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Israel Institute of Biblical Studies\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-11T15:41:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T11:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Blum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Blum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/\"},\"author\":{\"name\":\"Julia Blum\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\"},\"headline\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1)\",\"datePublished\":\"2018-04-11T15:41:41+00:00\",\"dateModified\":\"2025-08-13T11:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/\"},\"wordCount\":1244,\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/shutterstock_569066050.jpg\",\"articleSection\":[\"Estudios Jud\u00edos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/\",\"name\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/shutterstock_569066050.jpg\",\"datePublished\":\"2018-04-11T15:41:41+00:00\",\"dateModified\":\"2025-08-13T11:29:26+00:00\",\"description\":\"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/shutterstock_569066050.jpg\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/shutterstock_569066050.jpg\",\"width\":1000,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudios Jud\u00edos\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"name\":\"Israel Institute of Biblical Studies\",\"description\":\"Deepen Your Understanding of the Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\",\"name\":\"Israel Biblical Studies\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"width\":152,\"height\":68,\"caption\":\"Israel Biblical Studies\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\",\"name\":\"Julia Blum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"caption\":\"Julia Blum\"},\"description\":\"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/author\\\/juliablum\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies","description":"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/","og_locale":"es_ES","og_type":"article","og_title":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies","og_description":"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el","og_url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/","og_site_name":"Israel Institute of Biblical Studies","article_published_time":"2018-04-11T15:41:41+00:00","article_modified_time":"2025-08-13T11:29:26+00:00","og_image":[{"width":1000,"height":565,"url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg","type":"image\/jpeg"}],"author":"Julia Blum","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julia Blum","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#article","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/"},"author":{"name":"Julia Blum","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15"},"headline":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1)","datePublished":"2018-04-11T15:41:41+00:00","dateModified":"2025-08-13T11:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/"},"wordCount":1244,"publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg","articleSection":["Estudios Jud\u00edos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/","name":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1) - Israel Institute of Biblical Studies","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#primaryimage"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg","datePublished":"2018-04-11T15:41:41+00:00","dateModified":"2025-08-13T11:29:26+00:00","description":"\u00bfPOR QU\u00c9 JUD\u00c1? Muy pronto el Estado de Israel celebrar\u00e1 el 70\u00ba aniversario (El D\u00eda de la Independencia en Israel se celebra siempre de acuerdo con el","breadcrumb":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#primaryimage","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/04\/shutterstock_569066050.jpg","width":1000,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/israelbiblicalstudies.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estudios Jud\u00edos","item":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/"},{"@type":"ListItem","position":3,"name":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (1)"}]},{"@type":"WebSite","@id":"https:\/\/israelbiblicalstudies.com\/es\/#website","url":"https:\/\/israelbiblicalstudies.com\/es\/","name":"Israel Institute of Biblical Studies","description":"Deepen Your Understanding of the Bible","publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/israelbiblicalstudies.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization","name":"Israel Biblical Studies","url":"https:\/\/israelbiblicalstudies.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","width":152,"height":68,"caption":"Israel Biblical Studies"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15","name":"Julia Blum","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","caption":"Julia Blum"},"description":"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/author\/juliablum\/"}]}},"_links":{"self":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/12237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/comments?post=12237"}],"version-history":[{"count":0,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/12237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media\/12218"}],"wp:attachment":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media?parent=12237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/categories?post=12237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/tags?post=12237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}