{"id":45019,"date":"2018-05-11T14:57:14","date_gmt":"2018-05-11T11:57:14","guid":{"rendered":"https:\/\/iibsblogsstg.wpenginepowered.com\/?p=12281"},"modified":"2025-08-13T11:29:25","modified_gmt":"2025-08-13T11:29:25","slug":"retratos-biblicos-juda-4","status":"publish","type":"post","link":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/","title":{"rendered":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4)"},"content":{"rendered":"<p>Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar. \u00bfPor qu\u00e9 fue importante para nosotros ver esa transformaci\u00f3n? La Tor\u00e1 quiere asegurarse que sepamos que el Jud\u00e1 que llega a Egipto y habla a Jos\u00e9 no es el mismo Jud\u00e1 que vimos en el cap\u00edtulo 37, con la venta de Jos\u00e9. S\u00ed, la gran autoridad, el regalo especial que Dios da a Jud\u00e1 y a su tribu, todav\u00eda est\u00e1 all\u00ed, y lo veremos, pero este Jud\u00e1 tiene una personalidad completamente diferente \u2014los ojos de su coraz\u00f3n est\u00e1n abiertos\u2014. Y ahora, ser conscientes de este Jud\u00e1 transformado, nos lleva a la segunda parte de la historia, con el fin de completar nuestro retrato b\u00edblico.<\/p>\n<p><b><i>Esta angustia ha llegado a nosotros<\/i><\/b><\/p>\n<p>Ahora estamos en Egipto. El d\u00eda ha llegado finalmente, el momento tan esperado ha llegado, cuando los hermanos de Jos\u00e9 vienen a Egipto y se paran frente a \u00e9l \u2014los diez hermanos que casi lo asesinaron pero se apiadaron de \u00e9l para escuchar las sugerencias de Jos\u00e9 y venderlo como esclavo\u2014. Jos\u00e9 reconoci\u00f3 a sus hermanos, pero ellos no le reconocieron.<\/p>\n<p>A partir de este momento comienza un juego de gato y rat\u00f3n, o tal vez un juego de fr\u00edo y caliente; comienza a acontecer algo que no es tan visible desde el punto de vista de quien est\u00e1 afuera porque la historia principal est\u00e1 siendo disputada en el coraz\u00f3n de los participantes. A partir de ese momento, es como si una mano invisible se acercara sigilosamente a esa cosa profunda, oscura y prohibida que los hermanos hab\u00edan ocultado todos esos a\u00f1os, no solo de otros, sino tambi\u00e9n de ellos mismos. Cada escena, cada paso tomado en esta historia, llena sus corazones progresivamente con mayor confusi\u00f3n y miedo, en cada evento sucesivo, ellos sienten la mano invisible volvi\u00e9ndose \u201cm\u00e1s caliente\u201d, lenta pero seguramente se aproxima a ese secreto, enterrado en sus corazones.<\/p>\n<p>Leemos que Jos\u00e9 les habl\u00f3 \u00e1speramente, acus\u00e1ndolos de ser esp\u00edas y de llegar a ver la desnudez de su tierra. En un primer vistazo, todo lo que dijo Jos\u00e9 carece de alg\u00fan indicio de comprensi\u00f3n. \u00bfPor qu\u00e9 de repente los acusa de espionaje? \u00bfPor qu\u00e9 les dice que de esta manera ser\u00e1n probados y as\u00ed ver\u00e1 si hay algo de verdad en ellos: traigan a su hermano que actualmente no est\u00e1 con ustedes? Si ya los acus\u00f3, entonces \u00bfcu\u00e1l podr\u00eda ser la conexi\u00f3n entre el hermano que qued\u00f3 en la casa y la acusaci\u00f3n hecha contra ellos? Y sin embargo, a pesar de lo inesperado que esta acusaci\u00f3n podr\u00eda haberles parecido a ellos con su demanda posterior de buscar a su hermano menor, a pesar de su falta de sentido y la ausencia total de una conexi\u00f3n plausible con la acusaci\u00f3n misma, no les pareci\u00f3\u00a0irrazonable. Entonces se dijeron los unos a los otros: \u201csomos verdaderamente culpables por nuestro hermano, porque vimos la angustia de su alma cuando nos suplicaba, y no quisimos escuchar, por lo tanto, esta angustia ha llegado a nosotros\u201d.<\/p>\n<p>Esta angustia ha llegado a nosotros\u2026 o, como dijo Rub\u00e9n, \u201csu sangre ahora es demandada de nosotros\u201d. Observa c\u00f3mo Dios ahora no es mencionado aqu\u00ed \u2014a\u00fan no han entendido que ninguno menos el mismoTodopoderoso los ha hecho participantes en este juego\u2014. A\u00fan escuchamos las formas verbales impersonales y pasivas: su sangre ahora es demandada de nosotros\u00a0(\u05d3\u05de\u05d5 \u05e0\u05d3\u05e8\u05e9); ellos acreditan lo que est\u00e1 sucediendo a los caprichos y crueldades del gobernador egipcio, y por consiguiente, nada m\u00e1s que un desafortunado giro de eventos, y sin embargo\u2026 en sus rebajes internos, una curiosa conexi\u00f3n espiritual entre lo que les est\u00e1 sucediendo y esa historia antigua, ya comienza a revelarse. A trav\u00e9s de las circunstancias visibles aparentemente irracionales e inconsistentes, otra l\u00f3gica invisible comienza a abrirse camino hacia la superficie \u2014la l\u00f3gica del movimiento del Esp\u00edritu de Dios en el coraz\u00f3n de la persona que \u00e9l est\u00e1 buscando\u2014.<\/p>\n<p><b>\u00bfQu\u00e9 es esto que Dios nos ha hecho?<\/b><\/p>\n<p>Es interesante que, en este punto, las Escrituras no separan a Jud\u00e1 de sus hermanos \u2014vemos a toda la multitud unida y leemos que Jos\u00e9 est\u00e1 hablando a todos los hermanos\u2014 a los diez. Y a pesar de todo, sabemos que las Escrituras separaron a Jud\u00e1 antes y lo separar\u00e1n despu\u00e9s: lo vimos arrepentirse y confesar en su historia con Tamar, y veremos que ser\u00e1 el discurso y la confesi\u00f3n de Jud\u00e1 lo que tocar\u00e1 profundamente el coraz\u00f3n de Jos\u00e9 y har\u00e1 que se revele a sus hermanos. Entonces pienso que podemos concluir con seguridad que Jud\u00e1 es quien es m\u00e1s sensible al movimiento del esp\u00edritu de Dios en esta historia.<\/p>\n<p>Mientras tanto, diez hermanos emprendieron su regreso y uno de ellos nota la plata que hab\u00eda usado para pagar por el grano devuelto en su bolsa. Entonces sus corazones les fallaron y tuvieron miedo, dici\u00e9ndose unos a otros, \u201c\u00bfqu\u00e9 es esto que Dios nos ha hecho?\u201d \u00bfFue Jud\u00e1 quien pregunt\u00f3 eso? \u00bfFue \u00e9l quien comenz\u00f3 a entender que todo lo que les sucede no es simplemente un giro del destino, sino que Dios lo ha hecho a ellos. \u201c\u00bfQu\u00e9 es esto que Dios nos ha hecho?<\/p>\n<p>Mi querido lector, quiero que veas esta profunda transici\u00f3n: de \u201csu sangre es demandada\u201d a \u201c\u00bfqu\u00e9 es esto que Dios nos ha hecho?\u201d No es tan evidente en la mayor\u00eda de las traducciones, pero en hebreo esta transici\u00f3n es muy clara: de formas verbales impersonales y pasivas que describen solo circunstancias desafortunadas, a entender que es Dios quien se los est\u00e1 haciendo.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Aqu\u00ed el hebreo literalmente dice que \u201ctemblaron el uno al otro\u201d. Despu\u00e9s de todo, simplemente hab\u00edan dejado Egipto para comprar grano (al igual que muchos siglos despu\u00e9s la mujer samaritana fue simplemente al pozo en busca de agua) y ciertamente no esperaban, y mucho menos quer\u00edan, que algo inusual sucediera en este viaje. \u00bfPor qu\u00e9 les estaba sucediendo esas cosas tan extra\u00f1as? Como un rollo de pel\u00edcula doblemente expuesto con sus im\u00e1genes superpuestas, podemos ver la realidad de Dios, a\u00fan invisible, colocada sobre sus vidas rutinarias y comenzando a mostrarse. Y sin ninguna duda, Jud\u00e1, que ha experimentado la terrible tragedia de perder dos hijos, que se arrepinti\u00f3, que tiene un coraz\u00f3n quebrantado y humilde, es el m\u00e1s sensible entre los hermanos a esta realidad invisible de Dios.<\/p>\n<p>Continuar\u00e1\u2026<\/p>\n<p>Si te gusta este art\u00edculo, tal vez puedas disfrutar de mis libros, los puedes encontrar en mi p\u00e1gina:<b>\u00a0<\/b>https:\/\/israelbiblicalstudies.com\/blog\/author\/juliablum\/<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar. \u00bfPor qu\u00e9 fue importante para nosotros ver esa transformaci\u00f3n? La Tor\u00e1 quiere asegurarse que sepamos que el Jud\u00e1 que llega a Egipto y habla a Jos\u00e9 no es el mismo Jud\u00e1 [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":44829,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[565],"tags":[],"class_list":["post-45019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jewish-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies<\/title>\n<meta name=\"description\" content=\"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies\" \/>\n<meta property=\"og:description\" content=\"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Israel Institute of Biblical Studies\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-11T11:57:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T11:29:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Blum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Blum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/\"},\"author\":{\"name\":\"Julia Blum\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\"},\"headline\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4)\",\"datePublished\":\"2018-05-11T11:57:14+00:00\",\"dateModified\":\"2025-08-13T11:29:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/\"},\"wordCount\":1142,\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/test222.jpg\",\"articleSection\":[\"Estudios Jud\u00edos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/\",\"name\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/test222.jpg\",\"datePublished\":\"2018-05-11T11:57:14+00:00\",\"dateModified\":\"2025-08-13T11:29:25+00:00\",\"description\":\"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/test222.jpg\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/test222.jpg\",\"width\":360,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/retratos-biblicos-juda-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudios Jud\u00edos\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/category\\\/jewish-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"name\":\"Israel Institute of Biblical Studies\",\"description\":\"Deepen Your Understanding of the Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#organization\",\"name\":\"Israel Biblical Studies\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"width\":152,\"height\":68,\"caption\":\"Israel Biblical Studies\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\",\"name\":\"Julia Blum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"caption\":\"Julia Blum\"},\"description\":\"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/es\\\/blog\\\/author\\\/juliablum\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies","description":"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/","og_locale":"es_ES","og_type":"article","og_title":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies","og_description":"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.","og_url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/","og_site_name":"Israel Institute of Biblical Studies","article_published_time":"2018-05-11T11:57:14+00:00","article_modified_time":"2025-08-13T11:29:25+00:00","og_image":[{"width":360,"height":240,"url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg","type":"image\/jpeg"}],"author":"Julia Blum","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julia Blum","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#article","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/"},"author":{"name":"Julia Blum","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15"},"headline":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4)","datePublished":"2018-05-11T11:57:14+00:00","dateModified":"2025-08-13T11:29:25+00:00","mainEntityOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/"},"wordCount":1142,"publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg","articleSection":["Estudios Jud\u00edos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/","name":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4) - Israel Institute of Biblical Studies","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#primaryimage"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg","datePublished":"2018-05-11T11:57:14+00:00","dateModified":"2025-08-13T11:29:25+00:00","description":"Mis queridos lectores, juntos hemos sido testigos de una profunda transformaci\u00f3n interna que Jud\u00e1 atraves\u00f3 en el cap\u00edtulo 38, en su historia con Tamar.","breadcrumb":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#primaryimage","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2018\/05\/test222.jpg","width":360,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/retratos-biblicos-juda-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/israelbiblicalstudies.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estudios Jud\u00edos","item":"https:\/\/israelbiblicalstudies.com\/es\/blog\/category\/jewish-studies\/"},{"@type":"ListItem","position":3,"name":"RETRATOS B\u00cdBLICOS: JUD\u00c1 (4)"}]},{"@type":"WebSite","@id":"https:\/\/israelbiblicalstudies.com\/es\/#website","url":"https:\/\/israelbiblicalstudies.com\/es\/","name":"Israel Institute of Biblical Studies","description":"Deepen Your Understanding of the Bible","publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/israelbiblicalstudies.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/israelbiblicalstudies.com\/es\/#organization","name":"Israel Biblical Studies","url":"https:\/\/israelbiblicalstudies.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","width":152,"height":68,"caption":"Israel Biblical Studies"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/israelbiblicalstudies.com\/es\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15","name":"Julia Blum","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","caption":"Julia Blum"},"description":"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.","url":"https:\/\/israelbiblicalstudies.com\/es\/blog\/author\/juliablum\/"}]}},"_links":{"self":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/45019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/comments?post=45019"}],"version-history":[{"count":0,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/posts\/45019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media\/44829"}],"wp:attachment":[{"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/media?parent=45019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/categories?post=45019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/es\/wp-json\/wp\/v2\/tags?post=45019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}