{"id":11950,"date":"2017-10-11T10:24:40","date_gmt":"2017-10-11T07:24:40","guid":{"rendered":"https:\/\/iibsblogsstg.wpenginepowered.com\/?p=11950\/"},"modified":"2025-08-13T11:34:55","modified_gmt":"2025-08-13T11:34:55","slug":"ainda-sobre-o-sukkot","status":"publish","type":"post","link":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/","title":{"rendered":"Ainda sobre o Sukkot"},"content":{"rendered":"<p>Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 &#8211; 34:26.\u00a0Antes de fazer isso, no entanto, gostaria de esclarecer alguns termos relacionados a Festa: o que significa &#8220;dias intermedi\u00e1rios de Sukkot&#8221;?<\/p>\n<p>&nbsp;<\/p>\n<p>Em Lev\u00edtico 23, lemos sobre<em> Moadei<\/em> <em>Adonai\u00a0<\/em>\u2014as Festas B\u00edblicas, as \u00e9pocas especiais do Senhor encontrando com Seu povo\u2014.\u00a0Existem apenas duas Festas nesta lista que t\u00eam alguns dias entre o primeiro e o \u00faltimo dia do feriado.\u00a0N\u00f3s lemos que no primeiro e no s\u00e9timo dia da P\u00e1scoa dever\u00e1 ser &#8220;uma santa convoca\u00e7\u00e3o&#8221; e Shabbat-descanso sem trabalho, e no primeiro e oitavo dia da Festa dos Tabern\u00e1culos dever\u00e1 ser &#8220;uma santa convoca\u00e7\u00e3o&#8221; e Shabbat-descanso sem trabalho.\u00a0Os dias entre estes primeiros e \u00faltimos dias s\u00e3o chamados de &#8220;dias intermedi\u00e1rios&#8221; da festa:\u00a0 <em>Hol Hamoed<\/em>. Nestes dias cumprimentamos uns aos outros com as palavras: <em>Moadim leSimcha<\/em>\u00a0e muitas pessoas ainda trabalham, embora a atmosfera seja muito festiva e as pequenas barracas \u2014sukkot\u2014 estejam em toda parte.\u00a0\u00c9 costume \u2014e \u00e9 considerado uma grande ben\u00e7\u00e3o\u2014 ter convidados em seu sukkah.\u00a0Para aqueles que n\u00e3o viram isso, eu recomendo muito ver um maravilhoso filme de Israel <em>Ushpizin.<\/em><\/p>\n<p>Um dia intermedi\u00e1rio muito especial \u00e9 o s\u00e9timo dia de Sukkot, antes do final do feriado.\u00a0Chama-se\u00a0\u00a0Hoshana\u00a0Rabbah\u00a0e, embora ainda seja contado entre os dias de <em>Hol Hamoed, <\/em>\u00e9 considerado o \u00faltimo dia do &#8220;julgamento&#8221; divino, o dia em que os decretos do Yom Kippur e Rosh Hashana s\u00e3o finalizados.\u00a0Alguns textos Judeus o descrevem como um Dia do Julgamento semelhante ao pr\u00f3prio Yom Kippur.<\/p>\n<p>&nbsp;<\/p>\n<p>Outro dia intermedi\u00e1rio especial (para ambas as Festas) \u00e9, naturalmente, o Shabbat.\u00a0O texto da leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot \u00e9 retirado dos cap\u00edtulos 33-34 do \u00caxodo.\u00a0Nesta por\u00e7\u00e3o, Mois\u00e9s implora a Deus para que ele veja a gl\u00f3ria de Deus (Ex 33:18). Tamb\u00e9m nessa parte lemos sobre os Treze Atributos da Miseric\u00f3rdia, ou <em>Shelosh-&#8216;Esreh Middot HaRakhamim<\/em>\u00a0(\u05e9\u05b8\u05c1\u05dc\u05d5\u05b9\u05e9\u05c1 \u05e2\u05b6\u05e9\u05b0\u05c2\u05e8\u05b5\u05d4 \u05de\u05b4\u05d9\u05d3\u05d5\u05b9\u05ea \u05d4\u05e8\u05b7\u05d7\u05b2\u05de\u05b4\u05d9\u05dd\u00a0) (Ex. 34:6,7). Eu pessoalmente acredito que h\u00e1 nesta Escritura outra verdade profunda oferecida a n\u00f3s.<\/p>\n<p>&nbsp;<\/p>\n<p>O cap\u00edtulo 33 do \u00caxodo descreve os eventos que aconteceram logo ap\u00f3s o terr\u00edvel pecado de Israel \u2014logo ap\u00f3s o incidente do bezerro de ouro quando as t\u00e1buas foram quebradas por Mois\u00e9s\u2014.\u00a0No final do cap\u00edtulo anterior, vimos Mois\u00e9s intercedendo pelo povo e conseguindo convencer Deus a perdoar Israel.\u00a0J\u00e1 no in\u00edcio deste cap\u00edtulo, Mois\u00e9s recebe a confirma\u00e7\u00e3o de Deus: sim, ele permitir\u00e1 que Mois\u00e9s continue sua miss\u00e3o de levar o povo de Israel \u00e0 Terra Prometida, a terra que mana leite e mel.\u00a0No entanto, em Suas palavras ainda podemos ouvir o eco de Sua recente ira.\u00a0Ao mandar Mois\u00e9s e Israel partir para a Terra, ele diz: &#8220;<em>Suba a uma terra que mana leite e mel;\u00a0<strong>eu \u00a0n\u00e3o subirei no meio de ti, porque \u00e9s povo de dura cerviz, para que te n\u00e3o consuma eu no caminho<\/strong><\/em>\u201d.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Esta parece ser uma declara\u00e7\u00e3o definitiva, completamente clara e esperada, e completamente justa ap\u00f3s o terr\u00edvel pecado cometido pelo povo de Israel.\u00a0Qu\u00e3o grande deve ser a surpresa do leitor, no entanto, quando apenas v\u00e1rios vers\u00edculos depois lemos: &#8220;<em>E Ele disse:<\/em><strong><em> A Minha Presen\u00e7a ir\u00e1 contigo, e eu te darei descanso<\/em><\/strong>\u201d.<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> Como isto poderia ser poss\u00edvel?\u00a0Porquanto &#8220;<em>Ele n\u00e3o \u00e9 um homem, para que se arrependa<\/em>&#8220;<em>,<a href=\"#_ftn3\" name=\"_ftnref3\"><strong>[3]<\/strong><\/a><\/em> \u00a0ent\u00e3o, o que pode explicar essa mudan\u00e7a aparentemente contradit\u00f3ria e repentina de Sua decis\u00e3o?<\/p>\n<p>&nbsp;<\/p>\n<p>Este \u00e9 o mist\u00e9rio profundo de Sukkot: Sua santidade \u00e9 tal que Ele n\u00e3o pode habitar, nem ir, com pessoas pecaminosas e pecadoras, e ainda assim Ele escolhe morar e andar com o Seu povo, pois tal \u00e9 a Sua miseric\u00f3rdia.\u00a0Voc\u00ea j\u00e1 pensou em si mesmo como n\u00e3o merecedor da comunh\u00e3o de Deus?\u00a0Voc\u00ea j\u00e1 se perguntou como Deus ainda pode ser paciente com voc\u00ea e misericordioso com voc\u00ea, quando voc\u00ea mesmo teria desistido de voc\u00ea h\u00e1 muito tempo?\u00a0Basta pensar nisso: cada um de n\u00f3s conhece uma infinidade de raz\u00f5es pelas quais o Senhor poderia, e deveria, nos dizer: &#8220;<em>Eu \u00a0n\u00e3o subirei no meio de ti, porque \u00e9s povo de dura cerviz, para que te n\u00e3o consuma eu no caminho&#8221;<\/em>. Cada um de n\u00f3s merece plenamente essas palavras, cada um de n\u00f3s merece totalmente a recusa de Deus em ir conosco \u2014e cada um de n\u00f3s est\u00e1 plenamente ciente disso\u2014.\u00a0No entanto, mais do que qualquer coisa no mundo, cada um de n\u00f3s anseia ouvir suas palavras: &#8220;<em>A Minha Presen\u00e7a ir\u00e1 contigo, e eu te darei descanso<\/em>&#8221;\u00a0 \u2014e o incr\u00edvel \u00e9 que isto \u00e9 realmente o que Ele est\u00e1 nos dizendo\u2014. Esta \u00e9 a promessa espantosa de Deus para cada um de n\u00f3s, o mist\u00e9rio incompreens\u00edvel da Sua miseric\u00f3rdia: temos dura cerviz, n\u00e3o merecemos o Seu amor e a Sua miseric\u00f3rdia, e, no entanto, ele vem conosco e nos d\u00e1 descanso.<\/p>\n<p>&nbsp;<\/p>\n<p>Essa incr\u00edvel promessa de Sua miseric\u00f3rdia foi dada a Israel no deserto.\u00a0Infelizmente, muitas pessoas n\u00e3o se lembram disso.\u00a0Muitas vezes, n\u00e3o s\u00f3 nossos inimigos, mas tamb\u00e9m nossos amigos, \u00e0s vezes at\u00e9 n\u00f3s mesmos, vemos nosso povo como estando completamente abandonado e desamparado por Deus;\u00a0como caminhando sozinho atrav\u00e9s do vasto deserto de prova\u00e7\u00f5es e tristezas;\u00a0como aqueles a quem Deus disse:<em> &#8220;N\u00e3o irei no meio de voc\u00eas&#8230;&#8221; <\/em>E, de fato, estas foram Suas palavras para n\u00f3s, mas tamb\u00e9m foi para n\u00f3s que Ele disse:\u00a0<em>&#8220;A Minha Presen\u00e7a ir\u00e1 contigo, e eu te darei descanso&#8221; <\/em>\u2014e esta \u00e9 a parte mais importante\u2014. Desde ent\u00e3o, Sua Presen\u00e7a permaneceu com Israel em todos os lugares, e voc\u00ea percebe o que isso realmente significa?\u00a0Todos esses s\u00e9culos, em toda a dor e sofrimento que sofremos: nos massacres, nos guetos, nos campos de concentra\u00e7\u00e3o, em todos esses horr\u00edveis momentos (semanas, meses, anos) de completa solid\u00e3o e mis\u00e9ria, quando todos, incluindo n\u00f3s mesmos, parec\u00edamos estar totalmente abandonados \u2014na realidade, n\u00e3o est\u00e1vamos sozinhos\u2014.\u00a0O Senhor tem caminhado conosco.\u00a0<em>&#8220;Em toda a angustia deles foi ele angustiado, e o Anjo da Sua presen\u00e7a os salvou&#8221;.<a href=\"#_ftn4\" name=\"_ftnref4\"><strong>[4]<\/strong><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O mesmo \u00e9 verdade para todos n\u00f3s: pecadores e de dura cerviz, sabemos que n\u00e3o merecemos o Seu amor e a Sua miseric\u00f3rdia;\u00a0n\u00f3s sabemos que n\u00e3o merecemos Sua companhia \u2014e ainda que Ele venha conosco e nos d\u00ea descanso\u2014. \u00c9 por isso que essas palavras s\u00e3o sobre todos n\u00f3s \u2014s\u00e3o sobre voc\u00ea e eu\u2014.\u00a0N\u00e3o nos sentimos \u00e0s vezes completamente s\u00f3s e abandonados?\u00a0Todos pensamos \u00e0s vezes que toda esperan\u00e7a se foi e n\u00e3o h\u00e1 mais nada para esperar ou para ter esperan\u00e7a?\u00a0N\u00f3s, \u00e0s vezes, sentimos como se Deus escondesse o Seu rosto de n\u00f3s e n\u00e3o anda mais conosco?\u00a0Ent\u00e3o, Sua promessa \u00e9 para todos e cada um de n\u00f3s: &#8220;<em>A Minha Presen\u00e7a ir\u00e1 contigo, e eu te darei descanso<\/em>&#8220;.\u00a0Sua miseric\u00f3rdia, Sua presen\u00e7a com a gente e no nosso sukkot, nos nossos tabern\u00e1culos \u2014esse \u00e9 o motivo da nossa profunda alegria em Sukkot\u2014.<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> \u00caxodo 33:3<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> \u00caxodo 33:14<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> 1 Samuel 15:29<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Isa\u00edas 63:9<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Este artigo \u00e9 retirado do Pr\u00f3logo do meu novo livro,\u00a0<em>As Though Hiding His Face<\/em>. \u00a0Sei que alguns dos meus leitores est\u00e3o esperando por este livro sobre o Messias Oculto desde minha s\u00e9rie sobre o Messias Oculto neste blog;\u00a0estou feliz em dizer-lhes que o livro acaba de ser publicado e est\u00e1 dispon\u00edvel na Amazon e na minha p\u00e1gina neste blog: <a href=\"https:\/\/israelbiblicalstudies.com\/blog\/author\/juliablum\/.\">https:\/\/israelbiblicalstudies.com\/blog\/author\/juliablum\/.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 &#8211; 34:26.\u00a0Antes de fazer isso, no entanto, gostaria de esclarecer alguns termos relacionados a Festa: o que significa &#8220;dias intermedi\u00e1rios de Sukkot&#8221;? &nbsp; Em Lev\u00edtico 23, lemos sobre Moadei Adonai\u00a0\u2014as Festas B\u00edblicas, as \u00e9pocas especiais do [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":11946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[395],"tags":[],"class_list":["post-11950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jewish-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ainda sobre o Sukkot - Israel Institute of Biblical Studies<\/title>\n<meta name=\"description\" content=\"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ainda sobre o Sukkot - Israel Institute of Biblical Studies\" \/>\n<meta property=\"og:description\" content=\"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/\" \/>\n<meta property=\"og:site_name\" content=\"Israel Institute of Biblical Studies\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-11T07:24:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T11:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Blum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Blum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/\"},\"author\":{\"name\":\"Julia Blum\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\"},\"headline\":\"Ainda sobre o Sukkot\",\"datePublished\":\"2017-10-11T07:24:40+00:00\",\"dateModified\":\"2025-08-13T11:34:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/\"},\"wordCount\":1321,\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shutterstock_560729809.jpg\",\"articleSection\":[\"Estudos Judaicos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/\",\"name\":\"Ainda sobre o Sukkot - Israel Institute of Biblical Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shutterstock_560729809.jpg\",\"datePublished\":\"2017-10-11T07:24:40+00:00\",\"dateModified\":\"2025-08-13T11:34:55+00:00\",\"description\":\"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shutterstock_560729809.jpg\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shutterstock_560729809.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/ainda-sobre-o-sukkot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudos Judaicos\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ainda sobre o Sukkot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\",\"name\":\"Israel Institute of Biblical Studies\",\"description\":\"Deepen Your Understanding of the Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\",\"name\":\"Israel Biblical Studies\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"width\":152,\"height\":68,\"caption\":\"Israel Biblical Studies\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/person\\\/470c9356fa72a497ecb801267dff4d15\",\"name\":\"Julia Blum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g\",\"caption\":\"Julia Blum\"},\"description\":\"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/author\\\/juliablum\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ainda sobre o Sukkot - Israel Institute of Biblical Studies","description":"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/","og_locale":"pt_BR","og_type":"article","og_title":"Ainda sobre o Sukkot - Israel Institute of Biblical Studies","og_description":"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,","og_url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/","og_site_name":"Israel Institute of Biblical Studies","article_published_time":"2017-10-11T07:24:40+00:00","article_modified_time":"2025-08-13T11:34:55+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg","type":"image\/jpeg"}],"author":"Julia Blum","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julia Blum","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#article","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/"},"author":{"name":"Julia Blum","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15"},"headline":"Ainda sobre o Sukkot","datePublished":"2017-10-11T07:24:40+00:00","dateModified":"2025-08-13T11:34:55+00:00","mainEntityOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/"},"wordCount":1321,"publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg","articleSection":["Estudos Judaicos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/","url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/","name":"Ainda sobre o Sukkot - Israel Institute of Biblical Studies","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#primaryimage"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#primaryimage"},"thumbnailUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg","datePublished":"2017-10-11T07:24:40+00:00","dateModified":"2025-08-13T11:34:55+00:00","description":"Hoje vamos falar sobre a leitura da Tor\u00e1 para o Shabbat que cai nos dias intermedi\u00e1rios de Sukkot:\u00a0\u00caxodo 33:12 - 34:26.\u00a0Antes de fazer isso, no entanto,","breadcrumb":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#primaryimage","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2017\/10\/shutterstock_560729809.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/ainda-sobre-o-sukkot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/israelbiblicalstudies.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Estudos Judaicos","item":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/"},{"@type":"ListItem","position":3,"name":"Ainda sobre o Sukkot"}]},{"@type":"WebSite","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#website","url":"https:\/\/israelbiblicalstudies.com\/pt\/","name":"Israel Institute of Biblical Studies","description":"Deepen Your Understanding of the Bible","publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/israelbiblicalstudies.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization","name":"Israel Biblical Studies","url":"https:\/\/israelbiblicalstudies.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","width":152,"height":68,"caption":"Israel Biblical Studies"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/person\/470c9356fa72a497ecb801267dff4d15","name":"Julia Blum","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bba81953dcf8395e3b4a73607c07e2f9d3e53c113398ce1fd48361f3f137b781?s=96&d=mm&r=g","caption":"Julia Blum"},"description":"Julia is a teacher and an author of several books on biblical topics. She teaches two biblical courses at the Israel Institute of Biblical Studies, \u201cDiscovering the Hebrew Bible\u201d and \u201cJewish Background of the New Testament\u201d, and writes Hebrew insights for these courses.","url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/author\/juliablum\/"}]}},"_links":{"self":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts\/11950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/comments?post=11950"}],"version-history":[{"count":0,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts\/11950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/media\/11946"}],"wp:attachment":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/media?parent=11950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/categories?post=11950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/tags?post=11950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}