{"id":5698,"date":"2012-11-19T08:54:21","date_gmt":"2012-11-19T05:54:21","guid":{"rendered":"http:\/\/iibsblogs.wpengine.com\/?p=5698"},"modified":"2025-08-13T11:33:34","modified_gmt":"2025-08-13T11:33:34","slug":"reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25","status":"publish","type":"post","link":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/","title":{"rendered":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25)"},"content":{"rendered":"<p><strong>\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o levantarei. 20 Ent\u00e3o os judeus disseram: Em quarenta e seis anos foi edificado este templo, e tu o levantar\u00e1s em tr\u00eas dias? 21 Mas ele falava do templo do seu corpo. 22 Quando, pois, ressuscitou dentre os mortos , os seus disc\u00edpulos lembraram que ele tinha dito isso, e creram na Escritura e na palavra que Jesus tinha dito. 23 Ora, estando ele em Jerusal\u00e9m pela festa da P\u00e1scoa , muitos creram no seu nome, vendo os sinais que ele estava fazendo. 24 Jesus, por\u00e9m, de sua parte n\u00e3o confiava neles , porque a todos conhecia 25 e n\u00e3o precisava de que algu\u00e9m testemunhasse sobre o homem, pois ele bem sabia o que havia no homem\u201d.<\/strong><\/p>\n<p>A autoridade que Jesus demonstrou na a\u00e7\u00e3o prof\u00e9tica de limpeza do templo foi , mais uma vez destacando a quest\u00e3o b\u00e1sica que foi implicitamente perguntada &#8211; &#8220;Quem \u00e9 e quem deve estar no comando do povo de Deus , Israel&#8221;.\u00a0 Os evangelhos respondem previsivelmente:Jesus. O texto acima, vers\u00edculos 23 e 25 , n\u00e3o devem ser separados dos vers\u00edculos anteriores 13 ao 22 . Ambos descrevem a mesma coisa &#8211; Jerusal\u00e9m durante a P\u00e1scoa. Devemos ver o vers\u00edculo 23 e continuar aquilo que foi iniciado em Jerusal\u00e9m alguns vers\u00edculos antes. Em grego &#8220;Jesus de sua parte n\u00e3o confiava neles , porque conhecia todas as pessoas&#8221; poderiam e deveriam (por causa de todo o contexto) ser traduzido como &#8220;Jesus de sua parte n\u00e3o acredita neles , porque conhecia a todos eles&#8221;.\u00a0 (Jo.2:24) O que vem antes e o que se segue no relato evang\u00e9lico se encaixa muito melhor, dado este pequeno ajuste de tradu\u00e7\u00e3o, especialmente com o acompanhamento do vers\u00edculo 25 (e n\u00e3o precisava de ningu\u00e9m para testemunhar).<\/p>\n<p>Este tipo de f\u00f3rmula &#8220;show \/ nos dizer &#8221; (Jo.2:18 lemos &#8220;assim Hoi Ioudaioi (os judeus) disseram-lhe: Que sinal nos mostras para fazer essas coisas ?&#8221;) ser\u00e1 citada pelos Hoi Ioudaioi em v\u00e1rias ocasi\u00f5es e em todas as ocasi\u00f5es, o ponto era que eles (Hoi Ioudaioi ) eram formalmente encarregados da vida religiosa no antigo Israel sob ocupa\u00e7\u00e3o romana. A resposta de Jesus n\u00e3o poderia ter sido mais expl\u00edcito do que em 2:19 : &#8220;Destrua este templo, e em tr\u00eas dias eu o levantarei&#8221;. A autoridade da Hoi Ioudaioi n\u00e3o poderia ter sido mais desvalorizada. Este foi o caso, se foi entendido ou n\u00e3o foi como eles fizeram (2:20), ou deveriam ter feito (2:21). Sem se preocupar em explicar o que ele realmente quis dizer, Jesus negou a autoridade do hoi Ioudaioi (os judeus) em todo o Evangelho, mas especialmente nesta passagem.<\/p>\n<p>Um dos exemplos mais claros dessa din\u00e2nica \u00a8mostra nos \/ eu me recuso\u00a8 \u00e9 encontrado em Jo.10:24-27. Isso poderia at\u00e9 servir como um exemplo principal deste tipo de pol\u00eamica . Os Hoi Ioudaioi desafiaram Jesus para apresentar a sua candidatura para ser o Messias deles &#8211; os l\u00edderes Jerusalemite. Jesus recusou, dizendo que seu pai e seus pr\u00f3prios atos s\u00e3o suficientes para provar a sua autoridade, rejeitando assim a autoridade dos judeus (Hoi Ioudaioi):<\/p>\n<p>Hoi Ioudaioi se reuniram em torno dele, dizendo: &#8220;Quanto tempo voc\u00ea vai nos manter em suspense? Se voc\u00ea \u00e9 o Ungido, diga-nos abertamente&#8221;. Jesus respondeu: &#8220;J\u00e1 vo-lo tenho dito, e n\u00e3o o credes. As obras que eu fa\u00e7o, em nome de meu Pai, essas testificam de mim. Mas v\u00f3s n\u00e3o credes porque n\u00e3o sois das minhas ovelhas \u201d (Juan 10: 24-27).<\/p>\n<p>Este texto \u00e9 mais frequentemente lido como um exemplo de total falta de clareza de Jesus em declarar sua messianidade. No entanto, o autor atual sustenta que isto \u00e9 injustificado. O pedido de Hoi Ioudaioi n\u00e3o deve ser lido : &#8220;Quanto tempo voc\u00ea vai nos manter em suspense? Se voc\u00ea \u00e9 o Ungido, diga -nos abertamente&#8221;, mas &#8220;Quanto tempo voc\u00ea vai nos manter em suspense? Se voc\u00ea \u00e9 o Ungido, diga-nos abertamente&#8221;. Do ponto de vista de Hoi Ioudaioi , dada a sua autoridade religiosa como os representantes formais da religi\u00e3o judaica, a sua autoridade para validar a candidatura de Jesus para ser o Messias n\u00e3o estava sendo honrada.<\/p>\n<p>Jesus chamou a grandes multid\u00f5es que o seguiam . Os cegos viam, os coxos andavam, os leprosos foram curados, os surdos ouviram, e os mortos voltaram \u00e0 vida (Mat.11:2- 5). A identidade de Jesus como Messias era evidente, mas ele n\u00e3o conseguiu declarar-se como tal, para as autoridades de Jerusal\u00e9m. Esse foi o racioc\u00ednio por tr\u00e1s de sua demanda (quanto tempo voc\u00ea vai nos manter em suspense?). Ele, no entanto, sempre afirmou que seus milagres e, portanto, o testemunho de seu de sua messianidade, eram suficientes para estabelec\u00ea-lo como Servo messi\u00e2nico de Deus (Jo\u00e3o 10:25-42) . Jesus recusou-se a reconhecer a autoridade dos governantes de Jerusal\u00e9m sobre ele e, por extens\u00e3o, ao longo de toda a Israel. Jesus foi o \u00fanico a quem o Pactual Senhor de Israel confiou tal autoridade e, portanto, submeter-se \u00e0 autoridade de n\u00edvel ileg\u00edtimo\/ou pelo menos inferior dos Hoi Ioudaioi estava fora de quest\u00e3o (Matt.26 :63 -64).<\/p>\n<p>Ent\u00e3o o que aconteceu ? Simplesmente que os judeus (hoi Iudaioi) assumiram que eles tinham o direito de aprovar ou desaprovar Jesus. Eles j\u00e1 estavam envolvidos no processo de julg\u00e1-lo . Eles, na \u00e9poca, como fizeram mais explicitamente depois, desafiaram-no a provar-lhes quem ele era. Jesus recusou.<\/p>\n<p>\u00a9<a href=\"https:\/\/israelbiblicalstudies.com\/teacher\/eli-lizorkin-eyzenberg\/\"><strong> By Eli Lizorkin-Eyzenberg, Ph.D.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o levantarei. 20 Ent\u00e3o os judeus disseram: Em quarenta e seis anos foi edificado este templo, e tu o levantar\u00e1s em tr\u00eas dias? 21 Mas ele falava do [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[395],"tags":[],"class_list":["post-5698","post","type-post","status-publish","format-standard","hentry","category-jewish-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies<\/title>\n<meta name=\"description\" content=\"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies\" \/>\n<meta property=\"og:description\" content=\"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Israel Institute of Biblical Studies\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-19T05:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T11:33:34+00:00\" \/>\n<meta name=\"author\" content=\"Dr. Eli Lizorkin-Eyzenberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Eli Lizorkin-Eyzenberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/\"},\"author\":{\"name\":\"Dr. Eli Lizorkin-Eyzenberg\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/person\\\/b308f3a9234ec1941c13bda300eb6797\"},\"headline\":\"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25)\",\"datePublished\":\"2012-11-19T05:54:21+00:00\",\"dateModified\":\"2025-08-13T11:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/\"},\"wordCount\":929,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\"},\"articleSection\":[\"Estudos Judaicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/\",\"name\":\"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#website\"},\"datePublished\":\"2012-11-19T05:54:21+00:00\",\"dateModified\":\"2025-08-13T11:33:34+00:00\",\"description\":\"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudos Judaicos\",\"item\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/category\\\/jewish-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\",\"name\":\"Israel Institute of Biblical Studies\",\"description\":\"Deepen Your Understanding of the Bible\",\"publisher\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#organization\",\"name\":\"Israel Biblical Studies\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"contentUrl\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/logo-invert.png\",\"width\":152,\"height\":68,\"caption\":\"Israel Biblical Studies\"},\"image\":{\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/#\\\/schema\\\/person\\\/b308f3a9234ec1941c13bda300eb6797\",\"name\":\"Dr. Eli Lizorkin-Eyzenberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g\",\"caption\":\"Dr. Eli Lizorkin-Eyzenberg\"},\"description\":\"To secure your spot in our new course \u201cThe Jewish Background of New Testament\u201d - CLICK HERE NOW\",\"sameAs\":[\"https:\\\/\\\/israelbiblicalstudies.com\\\/teacher\\\/eli-lizorkin-eyzenberg\\\/\"],\"url\":\"https:\\\/\\\/israelbiblicalstudies.com\\\/pt\\\/blog\\\/author\\\/eli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies","description":"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/","og_locale":"pt_BR","og_type":"article","og_title":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies","og_description":"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o","og_url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/","og_site_name":"Israel Institute of Biblical Studies","article_published_time":"2012-11-19T05:54:21+00:00","article_modified_time":"2025-08-13T11:33:34+00:00","author":"Dr. Eli Lizorkin-Eyzenberg","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dr. Eli Lizorkin-Eyzenberg","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/#article","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/"},"author":{"name":"Dr. Eli Lizorkin-Eyzenberg","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/person\/b308f3a9234ec1941c13bda300eb6797"},"headline":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25)","datePublished":"2012-11-19T05:54:21+00:00","dateModified":"2025-08-13T11:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/"},"wordCount":929,"commentCount":0,"publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization"},"articleSection":["Estudos Judaicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/","url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/","name":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25) - Israel Institute of Biblical Studies","isPartOf":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#website"},"datePublished":"2012-11-19T05:54:21+00:00","dateModified":"2025-08-13T11:33:34+00:00","description":"\u201c18 Ent\u00e3o os judeus disseram -lhe: Que sinal nos mostras para fazer essas coisas ? 19 Respondeu-lhes Jesus : Derribai este templo, e em tr\u00eas dias eu o","breadcrumb":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/reinterpretando-se-voce-e-o-messias-diga-nos-claramente-joao-2-18-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/israelbiblicalstudies.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Estudos Judaicos","item":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/category\/jewish-studies\/"},{"@type":"ListItem","position":3,"name":"Reinterpretando, \u201cse voc\u00ea \u00e9 o Messias, diga-nos claramente (Jo\u00e3o 2: 18-25)"}]},{"@type":"WebSite","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#website","url":"https:\/\/israelbiblicalstudies.com\/pt\/","name":"Israel Institute of Biblical Studies","description":"Deepen Your Understanding of the Bible","publisher":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/israelbiblicalstudies.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#organization","name":"Israel Biblical Studies","url":"https:\/\/israelbiblicalstudies.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","contentUrl":"https:\/\/israelbiblicalstudies.com\/wp-content\/uploads\/2016\/09\/logo-invert.png","width":152,"height":68,"caption":"Israel Biblical Studies"},"image":{"@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/israelbiblicalstudies.com\/pt\/#\/schema\/person\/b308f3a9234ec1941c13bda300eb6797","name":"Dr. Eli Lizorkin-Eyzenberg","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/866277fd705ad3c0af8a46792a766d5b55b9bf38f5384a02812e8683e69e7ddf?s=96&d=mm&r=g","caption":"Dr. Eli Lizorkin-Eyzenberg"},"description":"To secure your spot in our new course \u201cThe Jewish Background of New Testament\u201d - CLICK HERE NOW","sameAs":["https:\/\/israelbiblicalstudies.com\/teacher\/eli-lizorkin-eyzenberg\/"],"url":"https:\/\/israelbiblicalstudies.com\/pt\/blog\/author\/eli\/"}]}},"_links":{"self":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts\/5698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/comments?post=5698"}],"version-history":[{"count":0,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/posts\/5698\/revisions"}],"wp:attachment":[{"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/media?parent=5698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/categories?post=5698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/israelbiblicalstudies.com\/pt\/wp-json\/wp\/v2\/tags?post=5698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}